{"id":16370,"date":"2023-02-22T10:31:05","date_gmt":"2023-02-22T09:31:05","guid":{"rendered":"https:\/\/52.31.48.128\/blog\/?p=16370"},"modified":"2025-02-19T11:40:52","modified_gmt":"2025-02-19T10:40:52","slug":"gastos-comunidad-local-comercial","status":"publish","type":"post","link":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/","title":{"rendered":"Qu\u00e9 gastos de comunidad pagan los locales comerciales"},"content":{"rendered":"\r\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 gastos de comunidad debe pagar un local comercial?<\/h2>\r\n\r\n\r\n\r\n<p>Normalmente los <a href=\"https:\/\/www.aedashomes.com\/obra-nueva-locales\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"locales comerciales (abre en una nueva pesta\u00f1a)\">locales comerciales<\/a> se encuentran insertos en comunidades de vecinos que <strong>se rigen por la Ley de Propiedad Horizontal (LPH).<\/strong> Es en esta ley donde se recogen las principales obligaciones que tienen los propietarios una vez se ha vendido el edificio completo por pisos y locales.<\/p>\r\n\r\n\r\n\r\n<p>Es ah\u00ed donde se puede ver <strong>qu\u00e9 gastos de comunidad deben pagar los locales comerciales. <\/strong>Si echamos un vistazo al art\u00edculo 9 de dicha ley podemos leer que el propietario debe \u201ccontribuir, con arreglo a la cuota de participaci\u00f3n fijada en el t\u00edtulo o a lo especialmente establecido, a los gastos generales para el adecuado sostenimiento del inmueble, sus servicios, cargas y responsabilidades que no sean susceptibles de individualizaci\u00f3n\u201d.<\/p>\r\n\r\n\r\n\r\n<p>Por lo general, cuando se constituye la comunidad de vecinos y por acuerdo de todos ellos, se lleva a cabo la<strong> elecci\u00f3n de la cuota de comunidad, <\/strong>aunque tambi\u00e9n puede ser fijada por resoluci\u00f3n judicial.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"601\" class=\"wp-image-16374\" src=\"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-de-local-comercial.png\" alt=\"Qu\u00e9 gastos de comunidad pagan los locales comerciales\" srcset=\"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-de-local-comercial.png 902w, https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-de-local-comercial-300x200.png 300w\" sizes=\"auto, (max-width: 902px) 100vw, 902px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u00bfExiste exoneraci\u00f3n de los gastos de comunidad a locales comerciales?<\/h2>\r\n\r\n\r\n\r\n<p>La respuesta es s\u00ed.<strong> Existen ciertos gastos comunitarios de los que el propietario del local comercial est\u00e1 exento<\/strong> por no estar dentro de las zonas comunes o no hacer uso de ellas. Ve\u00e1moslo con un ejemplo: imaginemos que el local se encuentra en la esquina del edificio. En este caso el propietario tiene una exoneraci\u00f3n de los gastos de la comunidad que tengan que ver con el mantenimiento del ascensor, pero tambi\u00e9n con la limpieza de la escalera al ser elementos de los que no se beneficia dicho local comercial.<\/p>\r\n\r\n\r\n\r\n<p>Aunque el concepto se engloba en la exoneraci\u00f3n de los gastos ordinarios por la conservaci\u00f3n y funcionamiento o los gastos extraordinarios por la instalaci\u00f3n, sustituci\u00f3n o reforma del elemento, no puede interpretarse a la ligera y<strong> viene regulado en el art\u00edculo 9 de la Ley de Propiedad Horizontal.<\/strong> Para la resoluci\u00f3n de dudas lo mejor es consultar a un administrador de fincas o un asesor experto.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 gastos de comunidad debe pagar un local comercial? Normalmente los locales comerciales se encuentran insertos en comunidades de vecinos que se rigen por la Ley de Propiedad Horizontal (LPH). Es en esta ley donde se recogen las principales obligaciones que tienen los propietarios una vez se ha vendido el edificio completo por pisos y&#8230;<\/p>\n","protected":false},"author":15,"featured_media":16373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[170],"tags":[441],"class_list":["post-16370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario-y-finanzas","tag-economia-domestica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 Qu\u00e9 gastos de comunidad paga un local comercial | AEDAS Homes<\/title>\n<meta name=\"description\" content=\"\u00bfSabes cu\u00e1les son los gastos de comunidad que tienen que pagar los locales comerciales? \u2705 \u00bfDe qu\u00e9 gastos puede estar exento un local? \u2b50\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 Qu\u00e9 gastos de comunidad paga un local comercial | AEDAS Homes\" \/>\n<meta property=\"og:description\" content=\"\u00bfSabes cu\u00e1les son los gastos de comunidad que tienen que pagar los locales comerciales? \u2705 \u00bfDe qu\u00e9 gastos puede estar exento un local? \u2b50\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/\" \/>\n<meta property=\"og:site_name\" content=\"AEDAS Homes Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aedashomes\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-22T09:31:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-19T10:40:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png\" \/>\n\t<meta property=\"og:image:width\" content=\"902\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"-\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"-\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/\"},\"author\":{\"name\":\"-\",\"@id\":\"https:\/\/www.aedashomes.com\/blog\/#\/schema\/person\/3943511ba2e912cf5f6ba43a52940713\"},\"headline\":\"Qu\u00e9 gastos de comunidad pagan los locales comerciales\",\"datePublished\":\"2023-02-22T09:31:05+00:00\",\"dateModified\":\"2025-02-19T10:40:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/\"},\"wordCount\":349,\"image\":{\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png\",\"keywords\":[\"Econom\u00eda dom\u00e9stica\"],\"articleSection\":[\"Econom\u00eda dom\u00e9stica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/\",\"url\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/\",\"name\":\"\u25b7 Qu\u00e9 gastos de comunidad paga un local comercial | AEDAS Homes\",\"isPartOf\":{\"@id\":\"https:\/\/www.aedashomes.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png\",\"datePublished\":\"2023-02-22T09:31:05+00:00\",\"dateModified\":\"2025-02-19T10:40:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.aedashomes.com\/blog\/#\/schema\/person\/3943511ba2e912cf5f6ba43a52940713\"},\"description\":\"\u00bfSabes cu\u00e1les son los gastos de comunidad que tienen que pagar los locales comerciales? \u2705 \u00bfDe qu\u00e9 gastos puede estar exento un local? \u2b50\",\"breadcrumb\":{\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#primaryimage\",\"url\":\"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png\",\"contentUrl\":\"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png\",\"width\":902,\"height\":595,\"caption\":\"gastos comunidad local comercial\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.aedashomes.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Econom\u00eda dom\u00e9stica\",\"item\":\"https:\/\/www.aedashomes.com\/blog\/inmobiliario-y-finanzas\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qu\u00e9 gastos de comunidad pagan los locales comerciales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aedashomes.com\/blog\/#website\",\"url\":\"https:\/\/www.aedashomes.com\/blog\/\",\"name\":\"AEDAS Homes Blog\",\"description\":\"El blog de la promotora inmobiliaria AEDAS Homes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aedashomes.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.aedashomes.com\/blog\/#\/schema\/person\/3943511ba2e912cf5f6ba43a52940713\",\"name\":\"-\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.aedashomes.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9a98fc972c3ec2b91fdfd2a81c93ee3fc7c04aeefac4d931b43205ed61d9e009?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9a98fc972c3ec2b91fdfd2a81c93ee3fc7c04aeefac4d931b43205ed61d9e009?s=96&d=mm&r=g\",\"caption\":\"-\"},\"url\":\"https:\/\/www.aedashomes.com\/blog\/author\/idento\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 Qu\u00e9 gastos de comunidad paga un local comercial | AEDAS Homes","description":"\u00bfSabes cu\u00e1les son los gastos de comunidad que tienen que pagar los locales comerciales? \u2705 \u00bfDe qu\u00e9 gastos puede estar exento un local? \u2b50","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/","og_locale":"es_ES","og_type":"article","og_title":"\u25b7 Qu\u00e9 gastos de comunidad paga un local comercial | AEDAS Homes","og_description":"\u00bfSabes cu\u00e1les son los gastos de comunidad que tienen que pagar los locales comerciales? \u2705 \u00bfDe qu\u00e9 gastos puede estar exento un local? \u2b50","og_url":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/","og_site_name":"AEDAS Homes Blog","article_publisher":"https:\/\/www.facebook.com\/aedashomes\/","article_published_time":"2023-02-22T09:31:05+00:00","article_modified_time":"2025-02-19T10:40:52+00:00","og_image":[{"width":902,"height":595,"url":"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png","type":"image\/png"}],"author":"-","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"-"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#article","isPartOf":{"@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/"},"author":{"name":"-","@id":"https:\/\/www.aedashomes.com\/blog\/#\/schema\/person\/3943511ba2e912cf5f6ba43a52940713"},"headline":"Qu\u00e9 gastos de comunidad pagan los locales comerciales","datePublished":"2023-02-22T09:31:05+00:00","dateModified":"2025-02-19T10:40:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/"},"wordCount":349,"image":{"@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png","keywords":["Econom\u00eda dom\u00e9stica"],"articleSection":["Econom\u00eda dom\u00e9stica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/","url":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/","name":"\u25b7 Qu\u00e9 gastos de comunidad paga un local comercial | AEDAS Homes","isPartOf":{"@id":"https:\/\/www.aedashomes.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#primaryimage"},"image":{"@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png","datePublished":"2023-02-22T09:31:05+00:00","dateModified":"2025-02-19T10:40:52+00:00","author":{"@id":"https:\/\/www.aedashomes.com\/blog\/#\/schema\/person\/3943511ba2e912cf5f6ba43a52940713"},"description":"\u00bfSabes cu\u00e1les son los gastos de comunidad que tienen que pagar los locales comerciales? \u2705 \u00bfDe qu\u00e9 gastos puede estar exento un local? \u2b50","breadcrumb":{"@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#primaryimage","url":"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png","contentUrl":"https:\/\/www.aedashomes.com\/blog\/wp-content\/uploads\/2023\/02\/gastos-comunidad-local-comercial.png","width":902,"height":595,"caption":"gastos comunidad local comercial"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aedashomes.com\/blog\/gastos-comunidad-local-comercial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.aedashomes.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Econom\u00eda dom\u00e9stica","item":"https:\/\/www.aedashomes.com\/blog\/inmobiliario-y-finanzas\/"},{"@type":"ListItem","position":3,"name":"Qu\u00e9 gastos de comunidad pagan los locales comerciales"}]},{"@type":"WebSite","@id":"https:\/\/www.aedashomes.com\/blog\/#website","url":"https:\/\/www.aedashomes.com\/blog\/","name":"AEDAS Homes Blog","description":"El blog de la promotora inmobiliaria AEDAS Homes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aedashomes.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.aedashomes.com\/blog\/#\/schema\/person\/3943511ba2e912cf5f6ba43a52940713","name":"-","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aedashomes.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9a98fc972c3ec2b91fdfd2a81c93ee3fc7c04aeefac4d931b43205ed61d9e009?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a98fc972c3ec2b91fdfd2a81c93ee3fc7c04aeefac4d931b43205ed61d9e009?s=96&d=mm&r=g","caption":"-"},"url":"https:\/\/www.aedashomes.com\/blog\/author\/idento\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/posts\/16370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/comments?post=16370"}],"version-history":[{"count":7,"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/posts\/16370\/revisions"}],"predecessor-version":[{"id":18352,"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/posts\/16370\/revisions\/18352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/media\/16373"}],"wp:attachment":[{"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/media?parent=16370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/categories?post=16370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aedashomes.com\/blog\/wp-json\/wp\/v2\/tags?post=16370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}